{"id":16236,"date":"2026-04-06T23:40:04","date_gmt":"2026-04-06T22:40:04","guid":{"rendered":"https:\/\/grillcentrum.shop\/gree\/produkt\/duzy-zestaw-mebli-ogrodowych-komplet-stol-ogrodowy-z-krzeslami-di-volio\/"},"modified":"2026-04-11T02:22:41","modified_gmt":"2026-04-11T01:22:41","slug":"duzy-zestaw-mebli-ogrodowych-komplet-stol-ogrodowy-z-krzeslami-di-volio","status":"publish","type":"product","link":"https:\/\/zenlavi.shop\/grill\/produkt\/duzy-zestaw-mebli-ogrodowych-komplet-stol-ogrodowy-z-krzeslami-di-volio\/","title":{"rendered":"Du\u017cy Zestaw Mebli Ogrodowych Komplet St\u00f3\u0142 Ogrodowy z Krzes\u0142ami di volio"},"content":{"rendered":"<div style=\"font-family: Arial, sans-serif; line-height: 1.6; color: #333; padding: 20px; clear: both; display: block; width: 100%; float: none; position: static; overflow: hidden;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h1>Ekskluzywne Meble Ogrodowe di volio Verona 8+1 \u2013 Zestaw z Hartowanym Szk\u0142em<\/h1>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Stw\u00f3rz eleganck\u0105 stref\u0119 jadalnian\u0105 na \u015bwie\u017cym powietrzu z zestawem <b>di volio Verona<\/b>. Ten nowoczesny komplet mebli ogrodowych dla 8 os\u00f3b to po\u0142\u0105czenie minimalistycznego designu, wytrzyma\u0142ego <b>technorattanu<\/b> oraz bezpiecznego <b>szk\u0142a hartowanego<\/b>. Zaprojektowany z my\u015bl\u0105 o funkcjonalno\u015bci i estetyce, zestaw doskonale wpisuje si\u0119 w aran\u017cacje nowoczesnych taras\u00f3w i ogrod\u00f3w. Dzi\u0119ki zastosowaniu materia\u0142\u00f3w odpornych na promieniowanie UV oraz zmienne warunki pogodowe, meble zachowuj\u0105 sw\u00f3j g\u0142\u0119boki kolor i nienaganny stan przez wiele lat u\u017cytkowania.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2000px;max-height:2000px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11658c\/ad94520b4f2da276a84f593392f7\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Stan-opakowania-oryginalne\" srcset=\"https:\/\/a.allegroimg.com\/original\/11658c\/ad94520b4f2da276a84f593392f7\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Stan-opakowania-oryginalne 360w,https:\/\/a.allegroimg.com\/original\/11658c\/ad94520b4f2da276a84f593392f7\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Stan-opakowania-oryginalne 720w,https:\/\/a.allegroimg.com\/original\/11658c\/ad94520b4f2da276a84f593392f7\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Stan-opakowania-oryginalne 1024w,https:\/\/a.allegroimg.com\/original\/11658c\/ad94520b4f2da276a84f593392f7\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Stan-opakowania-oryginalne 1440w,https:\/\/a.allegroimg.com\/original\/11658c\/ad94520b4f2da276a84f593392f7\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Stan-opakowania-oryginalne 2000w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2000px\" alt=\"Du\u017cy Zestaw Mebli Ogrodowych Komplet St\u00f3\u0142 Ogrodowy z Krzes\u0142ami di volio Stan opakowania oryginalne\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h2>Nowoczesna konstrukcja i kompletne wyposa\u017cenie 8+1<\/h2>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Zestaw Verona to idealne rozwi\u0105zanie dla os\u00f3b ceni\u0105cych presti\u017c i praktyczno\u015b\u0107. Najwa\u017cniejsze atuty, na kt\u00f3re warto zwr\u00f3ci\u0107 uwag\u0119:<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Du\u017ca pojemno\u015b\u0107:<\/b> Komfortowe miejsce przy stole dla 8 doros\u0142ych os\u00f3b.<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Szk\u0142o hartowane 5mm:<\/b> Wyj\u0105tkowo odporny blat, bezpieczny w u\u017cytkowaniu i \u0142atwy w piel\u0119gnacji.<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Plecionka technorattanowa:<\/b> R\u0119cznie wykonana, odporna na mr\u00f3z, deszcz i silne s\u0142o\u0144ce.<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Stalowa rama:<\/b> Solidna konstrukcja zapewniaj\u0105ca pe\u0142n\u0105 stabilno\u015b\u0107 i bezpiecze\u0144stwo.<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Poduszki z impregnacj\u0105:<\/b> Siedziska o grubo\u015bci 6 cm, kt\u00f3re nie wch\u0142aniaj\u0105 wilgoci i s\u0105 odporne na przetarcia.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2000px;max-height:2000px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/111ba0\/5fef10954077a77e15701de55474\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Material-dominujacy-technorattan\" srcset=\"https:\/\/a.allegroimg.com\/original\/111ba0\/5fef10954077a77e15701de55474\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Material-dominujacy-technorattan 360w,https:\/\/a.allegroimg.com\/original\/111ba0\/5fef10954077a77e15701de55474\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Material-dominujacy-technorattan 720w,https:\/\/a.allegroimg.com\/original\/111ba0\/5fef10954077a77e15701de55474\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Material-dominujacy-technorattan 1024w,https:\/\/a.allegroimg.com\/original\/111ba0\/5fef10954077a77e15701de55474\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Material-dominujacy-technorattan 1440w,https:\/\/a.allegroimg.com\/original\/111ba0\/5fef10954077a77e15701de55474\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Material-dominujacy-technorattan 2000w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2000px\" alt=\"Du\u017cy Zestaw Mebli Ogrodowych Komplet St\u00f3\u0142 Ogrodowy z Krzes\u0142ami di volio Materia\u0142 dominuj\u0105cy technorattan\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h2>Przestronny st\u00f3\u0142 z bezpiecznym, szklanym blatem<\/h2>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">G\u0142\u00f3wnym elementem zestawu jest <b>du\u017cy st\u00f3\u0142<\/b> o d\u0142ugo\u015bci 190 cm, wyposa\u017cony w blat z <b>czarnego szk\u0142a hartowanego o grubo\u015bci 5 mm<\/b>. Szklana powierzchnia nadaje meblom nowoczesny, luksusowy charakter i optycznie powi\u0119ksza przestrze\u0144 tarasu. Blat jest niezwykle odporny na zarysowania oraz uderzenia, a jego idealnie g\u0142adka struktura sprawia, \u017ce usuni\u0119cie plam po jedzeniu czy napojach wymaga jedynie przetarcia wilgotn\u0105 \u015bciereczk\u0105. To rozwi\u0105zanie idealne dla os\u00f3b, kt\u00f3re ceni\u0105 meble &#8222;bezobs\u0142ugowe&#8221;.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2000px;max-height:2000px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/111db0\/443bb0f94a5c81dc9a5558b1fba0\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kolor-bezowy\" srcset=\"https:\/\/a.allegroimg.com\/original\/111db0\/443bb0f94a5c81dc9a5558b1fba0\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kolor-bezowy 360w,https:\/\/a.allegroimg.com\/original\/111db0\/443bb0f94a5c81dc9a5558b1fba0\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kolor-bezowy 720w,https:\/\/a.allegroimg.com\/original\/111db0\/443bb0f94a5c81dc9a5558b1fba0\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kolor-bezowy 1024w,https:\/\/a.allegroimg.com\/original\/111db0\/443bb0f94a5c81dc9a5558b1fba0\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kolor-bezowy 1440w,https:\/\/a.allegroimg.com\/original\/111db0\/443bb0f94a5c81dc9a5558b1fba0\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kolor-bezowy 2000w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2000px\" alt=\"Du\u017cy Zestaw Mebli Ogrodowych Komplet St\u00f3\u0142 Ogrodowy z Krzes\u0142ami di volio Kolor be\u017cowy\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h2>Komfortowe fotele i tkaniny odporne na plamy<\/h2>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">W zestawie Verona komfort idzie w parze z trwa\u0142o\u015bci\u0105. Fotele posiadaj\u0105 ergonomiczny kszta\u0142t i mi\u0119kkie poduszki o grubo\u015bci 6 cm. Poszewki wykonano z wysokogatunkowej tkaniny poliestrowej, dodatkowo <b>zaimpregnowanej warstw\u0105 hydrofobow\u0105<\/b>. Dzi\u0119ki temu rozlane p\u0142yny nie wnikaj\u0105 w g\u0142\u0105b materia\u0142u, lecz tworz\u0105 krople na powierzchni, co zapobiega powstawaniu trwa\u0142ych zabrudze\u0144. Ka\u017cda poszewka posiada dyskretny zamek b\u0142yskawiczny, co umo\u017cliwia szybkie zdj\u0119cie i wypranie materia\u0142u w niskiej temperaturze.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2000px;max-height:2000px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11d3ac\/086874294f20b218e59fdf99f951\" srcset=\"https:\/\/a.allegroimg.com\/original\/11d3ac\/086874294f20b218e59fdf99f951 360w,https:\/\/a.allegroimg.com\/original\/11d3ac\/086874294f20b218e59fdf99f951 720w,https:\/\/a.allegroimg.com\/original\/11d3ac\/086874294f20b218e59fdf99f951 1024w,https:\/\/a.allegroimg.com\/original\/11d3ac\/086874294f20b218e59fdf99f951 1440w,https:\/\/a.allegroimg.com\/original\/11d3ac\/086874294f20b218e59fdf99f951 2000w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2000px\" alt=\"\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h2>Dane techniczne:<\/h2>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Marka: di volio<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Model: VERONA 8+1<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">St\u00f3\u0142 o wymiarach: d\u0142. 190&nbsp;cm \/&nbsp;szer. 90 cm \/&nbsp;wys. 74&nbsp;cm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Plecionka r\u0119czna z tworzywa PE, technorattan<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Stalowa rama<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Blat o grubo\u015bci 5mm ze szk\u0142a hartowanego<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Fotel: szer. 58,5 cm \/ g\u0142. 63,5 cm \/ wys. 86 cm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">G\u0142\u0119boko\u015b\u0107 siedziska: 45 cm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wysoko\u015b\u0107 n\u00f3\u017cek w krze\u015ble: 15 cm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wysoko\u015b\u0107 siedziska \/bez poduszki\/: 43 cm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wysoko\u015b\u0107 pod\u0142okietnika: 64 cm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Poduszki o grubo\u015bci 6&nbsp;cm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Poszewki&nbsp;z impregnowanego materia\u0142u, zapinane na zamek<\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Ze wzgl\u0119du na charakter materia\u0142u technorattanowego oraz r\u0119cznie wykonywanej plecionki na elementach zestawu, tolerancja wymiar\u00f3w wynosi +\/-5cm<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2000px;max-height:2000px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/111399\/a95d60ee42089e78a11df9e14d3e\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Zawartosc-zestawu-fotel-stol\" srcset=\"https:\/\/a.allegroimg.com\/original\/111399\/a95d60ee42089e78a11df9e14d3e\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Zawartosc-zestawu-fotel-stol 360w,https:\/\/a.allegroimg.com\/original\/111399\/a95d60ee42089e78a11df9e14d3e\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Zawartosc-zestawu-fotel-stol 720w,https:\/\/a.allegroimg.com\/original\/111399\/a95d60ee42089e78a11df9e14d3e\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Zawartosc-zestawu-fotel-stol 1024w,https:\/\/a.allegroimg.com\/original\/111399\/a95d60ee42089e78a11df9e14d3e\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Zawartosc-zestawu-fotel-stol 1440w,https:\/\/a.allegroimg.com\/original\/111399\/a95d60ee42089e78a11df9e14d3e\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Zawartosc-zestawu-fotel-stol 2000w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2000px\" alt=\"Du\u017cy Zestaw Mebli Ogrodowych Komplet St\u00f3\u0142 Ogrodowy z Krzes\u0142ami di volio Zawarto\u015b\u0107 zestawu fotel st\u00f3\u0142\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2000px;max-height:2000px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/111097\/dca5d6304430a5bfc62d54b7d107\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kod-producenta-DV-040GF\" srcset=\"https:\/\/a.allegroimg.com\/original\/111097\/dca5d6304430a5bfc62d54b7d107\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kod-producenta-DV-040GF 360w,https:\/\/a.allegroimg.com\/original\/111097\/dca5d6304430a5bfc62d54b7d107\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kod-producenta-DV-040GF 720w,https:\/\/a.allegroimg.com\/original\/111097\/dca5d6304430a5bfc62d54b7d107\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kod-producenta-DV-040GF 1024w,https:\/\/a.allegroimg.com\/original\/111097\/dca5d6304430a5bfc62d54b7d107\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kod-producenta-DV-040GF 1440w,https:\/\/a.allegroimg.com\/original\/111097\/dca5d6304430a5bfc62d54b7d107\/Duzy-Zestaw-Mebli-Ogrodowych-Komplet-Stol-Ogrodowy-z-Krzeslami-di-volio-Kod-producenta-DV-040GF 2000w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2000px\" alt=\"Du\u017cy Zestaw Mebli Ogrodowych Komplet St\u00f3\u0142 Ogrodowy z Krzes\u0142ami di volio Kod producenta DV-040GF\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n","protected":false},"excerpt":{"rendered":"<p>Ekskluzywne Meble Ogrodowe di volio Verona 8+1 \u2013 Zestaw z Hartowanym Szk\u0142em<\/p>\n","protected":false},"featured_media":16237,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[949],"product_cat":[532,542,541],"product_tag":[],"class_list":{"0":"post-16236","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-di-volio","7":"product_cat-komplety-mebli","8":"product_cat-meble-ogrodowe","9":"product_cat-ogrod","10":"product_shipping_class-transport-na-paletach","12":"first","13":"instock","14":"sale","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/zenlavi.shop\/grill\/wp-content\/uploads\/2026\/04\/allegro-image-16236.jpg",2000,2000,false],"thumbnail":["https:\/\/zenlavi.shop\/grill\/wp-content\/uploads\/2026\/04\/allegro-image-16236-150x150.jpg",150,150,true],"medium":["https:\/\/zenlavi.shop\/grill\/wp-content\/uploads\/2026\/04\/allegro-image-16236-300x300.jpg",300,300,true],"medium_large":["https:\/\/zenlavi.shop\/grill\/wp-content\/uploads\/2026\/04\/allegro-image-16236-768x768.jpg",768,768,true],"large":["https:\/\/zenlavi.shop\/grill\/wp-content\/uploads\/2026\/04\/allegro-image-16236-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/zenlavi.shop\/grill\/wp-content\/uploads\/2026\/04\/allegro-image-16236-1536x1536.jpg",1536,1536,true],"2048x2048":["https:\/\/zenlavi.shop\/grill\/wp-content\/uploads\/2026\/04\/allegro-image-16236.jpg",2000,2000,false],"woocommerce_thumbnail":["https:\/\/zenlavi.shop\/grill\/wp-content\/uploads\/2026\/04\/allegro-image-16236-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/zenlavi.shop\/grill\/wp-content\/uploads\/2026\/04\/allegro-image-16236-600x600.jpg",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/zenlavi.shop\/grill\/wp-content\/uploads\/2026\/04\/allegro-image-16236-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/zenlavi.shop\/grill\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Ekskluzywne Meble Ogrodowe di volio Verona 8+1 \u2013 Zestaw z Hartowanym Szk\u0142em","_links":{"self":[{"href":"https:\/\/zenlavi.shop\/grill\/wp-json\/wp\/v2\/product\/16236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenlavi.shop\/grill\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zenlavi.shop\/grill\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zenlavi.shop\/grill\/wp-json\/wp\/v2\/media\/16237"}],"wp:attachment":[{"href":"https:\/\/zenlavi.shop\/grill\/wp-json\/wp\/v2\/media?parent=16236"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zenlavi.shop\/grill\/wp-json\/wp\/v2\/product_brand?post=16236"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zenlavi.shop\/grill\/wp-json\/wp\/v2\/product_cat?post=16236"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zenlavi.shop\/grill\/wp-json\/wp\/v2\/product_tag?post=16236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}